{"id":17256,"date":"2026-03-13T14:18:32","date_gmt":"2026-03-13T13:18:32","guid":{"rendered":"https:\/\/help.mapal-os.com\/release-note-11-03-2026\/"},"modified":"2026-03-13T16:05:03","modified_gmt":"2026-03-13T15:05:03","slug":"release-note-11-03-2026","status":"publish","type":"post","link":"https:\/\/help.mapal-os.com\/es\/compliance\/release-note-11-03-2026\/","title":{"rendered":"Release note - 11.03.2026"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><em>Este sprint se centr\u00f3 en mejorar la visibilidad de la configuraci\u00f3n de tareas entre ubicaciones, reducir fricci\u00f3n en la configuraci\u00f3n de formularios y resolver varios problemas relacionados con la gesti\u00f3n de tareas, adjuntos, notificaciones y sincronizaci\u00f3n de usuarios.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\"><mark style=\"background-color:#9b51e0\" class=\"has-inline-color has-white-color\">Nuevas funcionalidades<\/mark><\/h1>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Reporte de tareas activas por ubicaci\u00f3n<\/strong><\/h3>\n\n\n\n<p>Ahora hay una nueva exportaci\u00f3n disponible en la p\u00e1gina <em>Structure<\/em> que muestra qu\u00e9 tareas centrales est\u00e1n activas en cada ubicaci\u00f3n. El reporte ofrece una visi\u00f3n centralizada de las tareas publicadas y su estado a nivel de ubicaci\u00f3n para identificar r\u00e1pidamente brechas de configuraci\u00f3n.<\/p>\n\n\n\n<p><strong>Por qu\u00e9 es importante<\/strong><\/p>\n\n\n\n<p>Hasta ahora no exist\u00eda una forma sencilla de verificar desde un punto central qu\u00e9 tareas estaban activas, pausadas o eliminadas en cada ubicaci\u00f3n. Esto dificultaba las auditor\u00edas y la revisi\u00f3n de la consistencia de la configuraci\u00f3n.<\/p>\n\n\n\n<p><strong>Beneficios clave<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mejora la visibilidad de la activaci\u00f3n de tareas por ubicaci\u00f3n<\/li>\n\n\n\n<li>Facilita la identificaci\u00f3n de inconsistencias de configuraci\u00f3n entre sitios<\/li>\n\n\n\n<li>Apoya auditor\u00edas y control del despliegue de tareas centrales<\/li>\n\n\n\n<li>Reduce revisiones manuales al comprobar la cobertura de tareas<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"591\" src=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-43-1024x591.png\" alt=\"\" class=\"wp-image-17244\" srcset=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-43-1024x591.png 1024w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-43-300x173.png 300w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-43-768x443.png 768w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-43-1536x886.png 1536w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-43.png 1640w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Activaci\u00f3n de multi-idioma durante la creaci\u00f3n de listas desplegables<\/strong><\/h3>\n\n\n\n<p>Los usuarios ahora pueden habilitar la opci\u00f3n <em>Multi-language<\/em> directamente al crear una nueva lista desplegable. Cuando est\u00e1 activada, la pesta\u00f1a <em>Localizations<\/em> se habilita inmediatamente dentro del mismo flujo de configuraci\u00f3n.<\/p>\n\n\n\n<p><strong>Por qu\u00e9 es importante<\/strong><\/p>\n\n\n\n<p>Antes, los usuarios ten\u00edan que guardar la lista primero y luego volver a editarla para configurar las traducciones, lo que a\u00f1ad\u00eda pasos innecesarios al proceso.<\/p>\n\n\n\n<p><strong>Beneficios clave<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Acelera la creaci\u00f3n de listas desplegables en entornos multi-idioma<\/li>\n\n\n\n<li>Reduce pasos innecesarios en el flujo de configuraci\u00f3n<\/li>\n\n\n\n<li>Permite configurar traducciones desde el inicio<\/li>\n\n\n\n<li>Mejora la experiencia de gesti\u00f3n global de formularios<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"581\" src=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-44-1024x581.png\" alt=\"\" class=\"wp-image-17245\" srcset=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-44-1024x581.png 1024w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-44-300x170.png 300w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-44-768x435.png 768w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-44-1536x871.png 1536w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2026\/03\/image-44.png 1663w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Compatibilidad del term\u00f3metro ETI en la PWA<\/strong><\/h3>\n\n\n\n<p><br>El term\u00f3metro ETI ahora es compatible con la aplicaci\u00f3n PWA. Esto ampl\u00eda la compatibilidad de dispositivos para clientes que realizan controles de temperatura dentro de sus procesos operativos.<\/p>\n\n\n\n<p><strong>Por qu\u00e9 es importante<\/strong><\/p>\n\n\n\n<p>Los usuarios que trabajaban en la PWA ten\u00edan limitaciones con ciertos dispositivos. Esta mejora aporta mayor flexibilidad en entornos operativos.<\/p>\n\n\n\n<p><strong>Beneficios clave<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ampl\u00eda la compatibilidad de hardware en la PWA<\/li>\n\n\n\n<li>Facilita los controles operativos de temperatura<\/li>\n\n\n\n<li>Mejora la consistencia de uso entre dispositivos<\/li>\n\n\n\n<li>Favorece la adopci\u00f3n de la PWA en tienda<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator alignwide has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\"><mark style=\"background-color:#9b51e0\" class=\"has-inline-color has-white-color\">Correccion de errores<\/mark><\/h1>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las descripciones largas en las opciones de desviaci\u00f3n ya no se truncar\u00e1n | Reduce el riesgo de seleccionar una desviaci\u00f3n incorrecta durante los formularios<\/li>\n\n\n\n<li>Corregido el problema de navegaci\u00f3n en las p\u00e1ginas de adjuntos al hacer clic en el nombre de la tarea | Restaura el contexto de navegaci\u00f3n correcto<\/li>\n\n\n\n<li>Corregido el problema al ordenar tareas en listas largas | Ahora los usuarios pueden reorganizar tareas correctamente<\/li>\n\n\n\n<li>Resuelto un problema de sincronizaci\u00f3n de usuarios | Mejora la fiabilidad en la creaci\u00f3n y sincronizaci\u00f3n de usuarios<\/li>\n\n\n\n<li>Mejora en el manejo de actualizaciones duplicadas de usuarios | Reduce errores causados por conflictos de registros de usuario<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este sprint se centr\u00f3 en mejorar la visibilidad de la configuraci\u00f3n de tareas entre ubicaciones, reducir fricci\u00f3n en la configuraci\u00f3n de formularios y resolver varios problemas relacionados con la gesti\u00f3n de tareas, adjuntos, notificaciones y sincronizaci\u00f3n de usuarios. Nuevas funcionalidades Reporte de tareas activas por ubicaci\u00f3n Ahora hay una nueva exportaci\u00f3n disponible en la p\u00e1gina [&hellip;]<\/p>\n","protected":false},"author":251318885,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[131546,132048,133077,132574],"tags":[],"class_list":["post-17256","post","type-post","status-publish","format-standard","hentry","category-compliance","category-whats-new-compliance","category-que-hay-de-nuevo-compliance","category-compliance-es"],"acf":{"article_type":"default","post_id":"","post_url_text":"","post_url":"","info_box":{"title":"","info":""},"post_video":"","import_category":"","overview_item":null,"troubleshoot_case":null},"_links":{"self":[{"href":"https:\/\/help.mapal-os.com\/es\/wp-json\/wp\/v2\/posts\/17256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.mapal-os.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.mapal-os.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/es\/wp-json\/wp\/v2\/users\/251318885"}],"replies":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/es\/wp-json\/wp\/v2\/comments?post=17256"}],"version-history":[{"count":0,"href":"https:\/\/help.mapal-os.com\/es\/wp-json\/wp\/v2\/posts\/17256\/revisions"}],"wp:attachment":[{"href":"https:\/\/help.mapal-os.com\/es\/wp-json\/wp\/v2\/media?parent=17256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.mapal-os.com\/es\/wp-json\/wp\/v2\/categories?post=17256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.mapal-os.com\/es\/wp-json\/wp\/v2\/tags?post=17256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}