{"id":10637,"date":"2025-01-16T14:13:39","date_gmt":"2025-01-16T13:13:39","guid":{"rendered":"https:\/\/help.mapal-os.com\/acceder-a-lapplication-workforce\/"},"modified":"2026-01-28T06:27:21","modified_gmt":"2026-01-28T05:27:21","slug":"accader-a-l-application-workforce","status":"publish","type":"post","link":"https:\/\/help.mapal-os.com\/fr\/workforce-fr\/workforce-app-2\/accader-a-l-application-workforce\/","title":{"rendered":"Acc\u00e9der \u00e0\u00a0 l'application Workforce"},"content":{"rendered":"<div data-wrapper=\"true\">\n<p><strong>Point de d\u00e9part : <\/strong>App Store, Google Play ou Huawei App Gallery.  <\/p>\n<ul>\n<li>\n<p>T\u00e9l\u00e9chargez l'<strong>application Workforce<\/strong> sur votre appareil mobile.<\/p>\n<\/li>\n<li>\n<p>Lorsque l'application est ouverte, l'<strong>\u00e9cran de connexion<\/strong> s'affiche.<\/p>\n<\/li>\n<li>\n<p>Saisissez l'<strong>adresse e-mail et le mot de passe<\/strong> de l'utilisateur Workforce et s\u00e9lectionnez le bouton<strong> Login<\/strong>.<\/p>\n<\/li>\n<\/ul>\n<p><strong>Remarques : <\/strong>L'empreinte digitale peut \u00e9galement \u00eatre utilis\u00e9e si votre p\u00e9riph\u00e9rique la prend en charge (la premi\u00e8re fois, vous devrez saisir vos identifiants).<\/p>\n<p>Une fois que l'utilisateur s'est authentifi\u00e9 avec succ\u00e8s, le panneau de contr\u00f4le de l'application Workforce s'affiche avec des cartes pour les fonctionnalit\u00e9s auxquelles l'utilisateur a acc\u00e8s. Par d\u00e9faut, les cartes visibles sont :<\/p>\n<ul>\n<li>\n<p><u>Personnel en shift<\/u> : Cette carte affiche les diff\u00e9rences entre le nombre d'employ\u00e9s avec un shift pr\u00e9vu au moment o\u00f9 le tableau est affich\u00e9 et le nombre d'entre eux qui ont point\u00e9 l'entr\u00e9e et sont actuellement pr\u00e9sents sur le site.<\/p>\n<\/li>\n<li>\n<p><u>Shifts<\/u> : La carte Shifts affiche les shifts de la semaine en cours pour tous les centres auxquels vous avez acc\u00e8s. Vous pouvez voir combien de shifts sont en attente de finalisation, ou lesquels sont d\u00e9finis comme termin\u00e9s, r\u00e9vis\u00e9s ou cl\u00f4tur\u00e9s.<\/p>\n<\/li>\n<li>\n<p><u>Absent\u00e9isme<\/u> : Dans l'onglet des incidents d'absent\u00e9isme, l'utilisateur peut voir, pour les centres auxquels il a acc\u00e8s, le nombre d'employ\u00e9s qui travaillent, en vacances, en arr\u00eat maladie ou en cong\u00e9 en raison de tout autre type d'incident.<\/p>\n<\/li>\n<\/ul>\n<p>De la m\u00eame mani\u00e8re, l'utilisateur pourra acc\u00e9der au menu central de l'application en s\u00e9lectionnant l'<strong>ic\u00f4ne Workforce<\/strong> visible sur l'\u00e9cran d'accueil.<\/p>\n<p>Lors de l'acc\u00e8s au menu, l'utilisateur pourra :<\/p>\n<ul>\n<li>\n<p><strong>Naviguez<\/strong> dans toutes les zones de l'application Workforce.<\/p>\n<\/li>\n<li>\n<p>D\u00e9connectez-vous en s\u00e9lectionnant l'option de menu <strong>Quitter<\/strong>.<\/p>\n<\/li>\n<li>\n<p>Si vous \u00eates un utilisateur multi-op\u00e9rateur, <strong>changez d'op\u00e9rateur<\/strong>.<\/p>\n<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L'application Workforce permet aux responsables du personnel de conserver un enregistrement clair du personnel en shift, des incidents, du temps de travail et d'autres \u00e9l\u00e9ments li\u00e9s au gestion de l'\u00e9quipe de travail. L'acc\u00e8s \u00e0 cette application est d'une grande importance pour assurer une gestion optimale du personnel.<\/p>\n","protected":false},"author":251210541,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[132224],"tags":[],"class_list":["post-10637","post","type-post","status-publish","format-standard","hentry","category-workforce-app-2"],"acf":{"article_type":"default","post_id":"KA-01273","post_url_text":"","post_url":"","info_box":{"title":"","info":""},"post_video":"","import_category":"","overview_item":null,"troubleshoot_case":null},"_links":{"self":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts\/10637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/users\/251210541"}],"replies":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/comments?post=10637"}],"version-history":[{"count":0,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts\/10637\/revisions"}],"wp:attachment":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/media?parent=10637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/categories?post=10637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/tags?post=10637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}