{"id":10807,"date":"2025-01-16T14:14:04","date_gmt":"2025-01-16T13:14:04","guid":{"rendered":"https:\/\/help.mapal-os.com\/creer-une-regle-de-decalage-de-production\/"},"modified":"2026-02-24T10:52:46","modified_gmt":"2026-02-24T09:52:46","slug":"craer-modifier-supprimer-des-ra-gles-de-shift-de-production","status":"publish","type":"post","link":"https:\/\/help.mapal-os.com\/fr\/easilys-fr\/production-1\/regles-de-decalage-de-production\/craer-modifier-supprimer-des-ra-gles-de-shift-de-production\/","title":{"rendered":"Cr\u00e9er, modifier, supprimer des r\u00e8gles de d\u00e9calage de production"},"content":{"rendered":"\n<p><strong>Remarque :<\/strong> chaque action effectu\u00e9e sur l'application est soumise \u00e0 des frais. Si vous ne parvenez pas \u00e0 effectuer les actions recommand\u00e9es dans les articles que vous consultez, cela peut signifier que les droits n\u00e9cessaires n'ont pas \u00e9t\u00e9 activ\u00e9s pour votre profil d'utilisateur. Contactez l'\u00e9quipe Support ou votre administrateur pour en savoir plus.<\/p>\n\n\n\n<p><strong>Start from:<\/strong> The Easilys menu.<\/p>\n\n\n\n<p>Une <strong>r\u00e8gle de d\u00e9calage de production* <\/strong>vous permet d'indiquer \u00e0 Easilys <strong>les r\u00e8gles \u00e0 suivre pour construire votre plan de production<\/strong> en fonction de vos menus ou en fonction des commandes que vos sites enfants ont pass\u00e9es aupr\u00e8s de vous si vous \u00eates en mode \u00ab flux labo \u00bb.<\/p>\n\n\n\n<p>Le principe est d'indiquer dans chaque r\u00e8gle <strong>combien de jours avant le jour pr\u00e9vu de consommation ou d'exp\u00e9dition il est n\u00e9cessaire de produire les recettes,<\/strong> rattach\u00e9es \u00e0 un atelier de production et \u00e0 un service particulier.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>S\u00e9lectionnez les onglets Production &gt; R\u00e8gles de d\u00e9calage de production.S\u00e9lectionnez + Cr\u00e9er.<\/li>\n\n\n\n<li>Affichez l'onglet <strong>Depuis les menus<\/strong> ou <strong>Depuis les commandes du site<\/strong> selon votre cas.<\/li>\n\n\n\n<li>S\u00e9lectionnez <strong>+ Cr\u00e9er<\/strong>.<span><span><span><span><span><span> <\/span><\/span><\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"232\" src=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T193706.277-1024x232.png\" alt=\"\" class=\"wp-image-9903\" srcset=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T193706.277-1024x232.png 1024w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T193706.277-300x68.png 300w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T193706.277-768x174.png 768w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T193706.277-1536x349.png 1536w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T193706.277.png 1864w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Compl\u00e9tez les <strong>\u00e9l\u00e9ments<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p><strong>Remarque :<\/strong> Pour cr\u00e9er des r\u00e8gles de d\u00e9calage de production plus rapidement, vous pouvez s\u00e9lectionner plusieurs ateliers, plusieurs jours et plusieurs types de repas dans l'\u00e9cran de cr\u00e9ation.<\/p>\n\n\n\n<p><strong>Exemple :<\/strong> Si vous livrez la veille de la consommation tous les plats des ateliers chaud et sauce pour les menus du mardi et du mercredi midi, en s\u00e9lectionnant ces \u00e9l\u00e9ments et en confirmant, le syst\u00e8me g\u00e9n\u00e9rera les quatre r\u00e8gles en une seule fois :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>D\u00e9jeuner chaud du mardi \u2013 2 jours avant<\/li>\n\n\n\n<li>Sauce du d\u00e9jeuner de mardi \u2013 2 jours avant<\/li>\n\n\n\n<li>D\u00e9jeuner chaud du mercredi \u2013 2 jours avant<\/li>\n\n\n\n<li>Sauce du d\u00e9jeuner de mercredi \u2013 2 jours avant<\/li>\n<\/ol>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Confirmez la<strong> cr\u00e9ation de la r\u00e8gle<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p>Pour <strong>modifier\/supprimer une r\u00e8gle<\/strong>, plusieurs m\u00e9thodes sont possibles :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cliquez sur la r\u00e8gle puis sur <strong>Modifier<\/strong> ou <strong>Supprimer<\/strong><\/li>\n\n\n\n<li>Cliquez sur les <strong>\u2026<\/strong> \u00e0 la fin de la ligne, puis choisissez l'option <strong>Modifier<\/strong> ou <strong>Supprimer<\/strong><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"288\" src=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194511.447-1024x288.png\" alt=\"\" class=\"wp-image-9905\" srcset=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194511.447-1024x288.png 1024w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194511.447-300x84.png 300w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194511.447-768x216.png 768w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194511.447-1536x432.png 1536w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194511.447.png 1815w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Pour <strong>modifier\/supprimer plusieurs r\u00e8gles<\/strong> \u00e0 la fois :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>V\u00e9rifiez les r\u00e8gles concern\u00e9es<\/li>\n\n\n\n<li>Cliquez sur <strong>Actions<\/strong><\/li>\n\n\n\n<li>Choisissez l'action souhait\u00e9e<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"230\" src=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194515.733-1024x230.png\" alt=\"\" class=\"wp-image-9906\" srcset=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194515.733-1024x230.png 1024w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194515.733-300x67.png 300w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194515.733-768x173.png 768w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194515.733-1536x345.png 1536w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/image-2025-10-02T194515.733.png 1784w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Remarque :<\/strong> si vous effectuez une action de modification en masse, les r\u00e8gles s\u00e9lectionn\u00e9es seront supprim\u00e9es et remplac\u00e9es par les nouvelles r\u00e8gles r\u00e9sultant des informations saisies dans l'\u00e9cran de modification.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En tant que responsable d'un restaurant produisant des plats froids, vous devez cr\u00e9er des r\u00e8gles de d\u00e9calage pour permettre \u00e0 Easilys de g\u00e9n\u00e9rer un plan de production conforme \u00e0 votre organisation de travail. Ce guide vous accompagne tout au long du processus.<\/p>\n","protected":false},"author":251210541,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[132369],"tags":[],"class_list":["post-10807","post","type-post","status-publish","format-standard","hentry","category-regles-de-decalage-de-production"],"acf":{"article_type":"default","post_id":"KA-01621","post_url_text":"Dashboard > Production > Production postponement rules > Create","post_url":"\/v2\/#\/production-time-lag-rules","info_box":{"title":"","info":""},"post_video":"","import_category":"","overview_item":null,"troubleshoot_case":null},"_links":{"self":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts\/10807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/users\/251210541"}],"replies":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/comments?post=10807"}],"version-history":[{"count":0,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts\/10807\/revisions"}],"wp:attachment":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/media?parent=10807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/categories?post=10807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/tags?post=10807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}