{"id":10937,"date":"2025-01-16T14:13:24","date_gmt":"2025-01-16T13:13:24","guid":{"rendered":"https:\/\/help.mapal-os.com\/definir-les-autorisations-pour-les-responsables-de-formation\/"},"modified":"2026-01-26T11:51:36","modified_gmt":"2026-01-26T10:51:36","slug":"dafinir-les-autorisations-pour-les-responsables-de-formation","status":"publish","type":"post","link":"https:\/\/help.mapal-os.com\/fr\/flow-learning-fr\/entreprise\/managers-1\/dafinir-les-autorisations-pour-les-responsables-de-formation\/","title":{"rendered":"D\u00e9finir les autorisations pour les responsables de formation"},"content":{"rendered":"<div data-wrapper=\"true\"><strong>Remarque : <\/strong>Votre plateforme Flow n\u2019applique pas forc\u00e9ment toutes les autorisations. N'h\u00e9sitez pas \u00e0 nous contacter si vous souhaitez en savoir plus sur les diff\u00e9rentes fonctionnalit\u00e9s disponibles sur la plateforme Flow.<\/p>\n<h2>Ajouter des autorisations de responsable de formation via Mapal OS<\/h2>\n<p>Pour les utilisateurs sur Mapal OS, vos autorisations doivent d\u00e9sormais \u00eatre g\u00e9r\u00e9es en tant que profils d'utilisateur sur le tableau de bord Mapal OS. Consultez notre guide d\u00e9taill\u00e9 sur <a href=\"https:\/\/mapalcustomerselfservice.powerappsportals.com\/en-us\/knowledgebase\/article\/KA-01675\">Synchroniser les autorisations dans Mapal OS et Flow Learning<\/a>. <strong>Remarque :<\/strong> si vous n'\u00eates pas s\u00fbr d'\u00eatre sur Mapal OS, contactez votre Customer Success Manager.<\/p>\n<h2>G\u00e9rer les gestionnaires de compte sur Mapal OS<\/h2>\n<p>Les gestionnaires de compte disposent du niveau d'acc\u00e8s le plus \u00e9lev\u00e9 sur Mapal OS et ne peuvent pas \u00eatre configur\u00e9s manuellement. Si vous devez configurer un utilisateur avec des autorisations de gestionnaire de compte, contactez simplement votre Customer Success Manager.<\/p>\n<h2>Ajouter des autorisations de responsable de formation via Flow MS<\/h2>\n<p><strong>Point de d\u00e9part : <\/strong>Le tableau de bord Flow.<\/p>\n<ul>\n<li data-wrapper=\"true\">S\u00e9lectionnez <strong>Entreprise&gt;Managers<\/strong>. <\/li>\n<li data-wrapper=\"true\">S\u00e9lectionnez <strong>Ajouter<\/strong>. <\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"width: 1917px; height: 1080px;\" src=\"\/wp-content\/uploads\/2025\/migration\/KA-01091\/img0.jpg\" alt=\"\" width=\"1917\" height=\"1080\" align=\"none\" data-msdynid=\"___06ebe84c-1d74-ee11-8179-6045bd8f972b___\" data-msdyntype=\"data:image\/png;base64\"><\/p>\n<ul>\n<li data-wrapper=\"true\">Saisissez les coordonn\u00e9es du responsable de formation dans les champs pr\u00e9nom, nom et e-mail. <strong>Remarque :<\/strong> Ces trois champs sont obligatoires. <\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"width: 1917px; height: 1080px;\" src=\"\/wp-content\/uploads\/2025\/migration\/KA-01091\/img1.jpg\" alt=\"\" width=\"1917\" height=\"1080\" align=\"none\" data-msdynid=\"___d5bcf983-1e74-ee11-8179-6045bd8f972b___\" data-msdyntype=\"data:image\/png;base64\"><\/p>\n<ul>\n<li>S\u00e9lectionnez \u201cLe manager est actif ?\u201d : cela permet au manager de se connecter activement \u00e0 Flow. <\/li>\n<li>S\u00e9lectionnez le <strong>profil d'autorisation<\/strong> dans le menu d\u00e9roulant. <strong>Remarque :<\/strong> Vous pouvez d\u00e9finir diff\u00e9rents profils d\u2019autorisation \u00e0 s\u00e9lectionner dans ce menu d\u00e9roulant, via <strong>Entreprise &gt; Param\u00e8tres utilisateur &gt; Gestion des profils d'autorisation<\/strong>. <\/li>\n<li>S\u00e9lectionnez un profil d'autorisations pr\u00e9d\u00e9fini.<\/li>\n<\/ul>\n<h3>Droits d'acc\u00e8s<\/h3>\n<p>Pour g\u00e9rer les diff\u00e9rentes options d'autorisations, vous pouvez utiliser les profils d'autorisations. Pour en savoir plus, consultez <a href=\"\/fr\/?p=12175\">g\u00e9rer les profils d'autorisations.<\/a><\/p>\n<h3>Sections, divisions, r\u00e9gions, zones, branches et d\u00e9partements<\/h3>\n<ul>\n<li>S\u00e9lectionnez<strong> Tous<\/strong> pour que le nouveau responsable de formation ait acc\u00e8s \u00e0 tout. <\/li>\n<li>S\u00e9lectionnez <strong>Particulier<\/strong>, pour donner au nouveau responsable de formation l'acc\u00e8s \u00e0 des sections, divisions, r\u00e9gions, zones, branches ou d\u00e9partements particuliers. <\/li>\n<\/ul>\n<h3>Enregistrez vos param\u00e8tres<\/h3>\n<ul>\n<li>S\u00e9lectionnez <strong>Sauvegarder<\/strong> pour confirmer et ajouter le nouveau responsable de formation. Vous verrez que le nouveau responsable sera ajout\u00e9 \u00e0 la liste des responsables de formation. <\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00f4le d'un responsable de formation sur la plateforme d'apprentissage Flow est de superviser et de g\u00e9rer les apprenants, de suivre les progr\u00e8s et de s'assurer que les exigences de l'entreprise en mati\u00e8re de formation sont respect\u00e9es. Les responsables de formation peuvent \u00eatre ajout\u00e9s au syst\u00e8me \u00e0 l'aide d'une s\u00e9rie de choix d'autorisations qui d\u00e9pendent de l'\u00e9tendue de l'acc\u00e8s que vous souhaitez donner \u00e0 votre responsable.<\/p>\n","protected":false},"author":251210541,"featured_media":10938,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[132181,132363],"tags":[],"class_list":["post-10937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-managers-1","category-profils-utilisateurs"],"acf":{"article_type":"default","post_id":"KA-01091","post_url_text":"","post_url":"\/c\/{flw_operator_code}\/settings\/users\/","info_box":{"title":"","info":""},"post_video":"","import_category":"","overview_item":null,"troubleshoot_case":null},"_links":{"self":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts\/10937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/users\/251210541"}],"replies":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/comments?post=10937"}],"version-history":[{"count":0,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts\/10937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/media\/10938"}],"wp:attachment":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/media?parent=10937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/categories?post=10937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/tags?post=10937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}