{"id":12117,"date":"2025-01-16T14:14:27","date_gmt":"2025-01-16T13:14:27","guid":{"rendered":"https:\/\/help.mapal-os.com\/?p=12117"},"modified":"2026-01-26T11:57:24","modified_gmt":"2026-01-26T10:57:24","slug":"garer-les-employas-dans-mapal-os","status":"publish","type":"post","link":"https:\/\/help.mapal-os.com\/fr\/mapal-os-fr\/gestion-des-employes\/employes-1\/garer-les-employas-dans-mapal-os\/","title":{"rendered":"G\u00e9rer les employ\u00e9s dans Mapal OS"},"content":{"rendered":"\n\n<p><strong>Point de d\u00e9part : <\/strong>Le tableau de bord Configuration.<\/p>\n\n\n\n\n\n\n<ul class=\"wp-block-list\">\n\n<li>Acc\u00e9dez \u00e0 <strong>Pilotage des Employ\u00e9s &gt; Employ\u00e9s<\/strong>.<\/li>\n<\/ul>\n\n\n\n\n\n\n<p>Le tableau <strong>Employ\u00e9s<\/strong> affiche les d\u00e9tails cl\u00e9s de chaque fiche employ\u00e9, tels que :<\/p>\n\n\n\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Colonne<\/strong><\/th><th><strong>Description<\/strong><\/th><\/tr><\/thead><tbody><tr><td><strong>Name<\/strong><\/td><td>Le nom complet de l'employ\u00e9 tel qu'enregistr\u00e9 dans le syst\u00e8me.<\/td><\/tr><tr><td><strong>Job Title<\/strong><\/td><td>Le r\u00f4le actuel de l'employ\u00e9 au sein de l'organisation.<\/td><\/tr><tr><td><strong>Sites<\/strong><\/td><td>Le site, la branche ou l'emplacement auquel l'employ\u00e9 est attribu\u00e9.<\/td><\/tr><tr><td><strong>Department<\/strong><\/td><td>Le d\u00e9partement auquel appartient l'employ\u00e9 (par exemple, Cuisine, RH, Op\u00e9rations).<\/td><\/tr><tr><td><strong>Date de d\u00e9but<\/strong><\/td><td>La date de d\u00e9but officielle de l'employ\u00e9 au sein de l'organisation.<\/td><\/tr><tr><td><strong>Statut<\/strong><\/td><td>Affiche si l'employ\u00e9 est <em>Employ\u00e9<\/em>, <em>Non employ\u00e9<\/em>, ou <em>Pas encore commenc\u00e9<\/em>, en fonction de sa p\u00e9riode d'emploi.<\/td><\/tr><tr><td><strong>Utilisateur li\u00e9<\/strong><\/td><td>Indique si l'employ\u00e9 est connect\u00e9 \u00e0 un profil d'utilisateur Mapal OS (<em>Oui<\/em> \/ <em>Non<\/em>). Un utilisateur li\u00e9 a acc\u00e8s aux produits Mapal OS selon ses autorisations.<\/td><\/tr><tr><td><strong>Actions (?)<\/strong><\/td><td>Utilisez le menu \u00e0 trois points pour <strong>Modifier<\/strong> ou <strong>Supprimer<\/strong> la fiche de l'employ\u00e9.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n\n\n\n<p><strong>Remarque :<\/strong> Par d\u00e9faut, seuls les employ\u00e9s ayant le statut <strong>Actuellement employ\u00e9<\/strong> sont affich\u00e9s. Vous pouvez ajuster les options de filtre pour inclure les employ\u00e9s <em>Non employ\u00e9<\/em> ou <em>Pas encore commenc\u00e9<\/em> si n\u00e9cessaire.<\/p>\n\n\n\n\n\n\n<p>Pour ajouter de nouveaux employ\u00e9s, consultez <strong><a href=\"https:\/\/help.mapal-os.com\/fr\/uncategorised\/ajouter-un-nouvel-employe-a-un-operateur-dans-mapal-os\/\">Ajouter un nouvel employ\u00e9 \u00e0 un op\u00e9rateur dans Mapal OS<\/a><\/strong>.<\/p>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Modifier les informations d'un employ\u00e9<\/h2>\n\n\n\n\n\n\n<ul class=\"wp-block-list\">\n\n<li>Trouvez l'employ\u00e9. Vous pouvez utiliser le <strong>Filtre<\/strong> pour affiner votre recherche <strong>OU<\/strong> le bouton <strong>Rechercher<\/strong> pour trouver des noms sp\u00e9cifiques.<\/li>\n\n\n\n\n\n\n<li>Une fois que vous avez trouv\u00e9 l'employ\u00e9, s\u00e9lectionnez le <strong>bouton \u00e0 trois points<\/strong> \u00e0 l'extr\u00eame droite de la ligne et appuyez sur l'option <strong>Modifier<\/strong>.<\/li>\n<\/ul>\n\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"585\" src=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/Captura-de-pantalla-2025-10-27-a-las-6.57.21-p.m-1024x585.png\" alt=\"\" class=\"wp-image-10368\" srcset=\"https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/Captura-de-pantalla-2025-10-27-a-las-6.57.21-p.m-1024x585.png 1024w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/Captura-de-pantalla-2025-10-27-a-las-6.57.21-p.m-300x171.png 300w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/Captura-de-pantalla-2025-10-27-a-las-6.57.21-p.m-768x439.png 768w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/Captura-de-pantalla-2025-10-27-a-las-6.57.21-p.m-1536x878.png 1536w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/Captura-de-pantalla-2025-10-27-a-las-6.57.21-p.m-2048x1171.png 2048w, https:\/\/help.mapal-os.com\/wp-content\/uploads\/2025\/01\/Captura-de-pantalla-2025-10-27-a-las-6.57.21-p.m-scaled.png 2560w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n\n\n\n<ul class=\"wp-block-list\">\n\n<li>Une barre lat\u00e9rale s'ouvrira avec les informations de l'employ\u00e9. Vous pouvez y modifier les champs suivants :<\/li>\n<\/ul>\n\n\n\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Champ<\/th><th>Description<\/th><\/tr><\/thead><tbody><tr><td><strong>Pr\u00e9nom (Obligatoire)<\/strong><\/td><td>Le pr\u00e9nom de l'employ\u00e9.<\/td><\/tr><tr><td><strong>Nom<\/strong><\/td><td>Le nom de famille de l'employ\u00e9.<\/td><\/tr><tr><td><strong>E-mail<\/strong><\/td><td>L'adresse e-mail professionnelle de l'employ\u00e9 utilis\u00e9e pour les notifications et l'acc\u00e8s.<\/td><\/tr><tr><td><strong>Site (Obligatoire)<\/strong><\/td><td>Le site ou l'emplacement auquel l'employ\u00e9 appartient.<\/td><\/tr><tr><td><strong>Intitul\u00e9 de poste (Obligatoire)<\/strong><\/td><td>Le r\u00f4le de l'employ\u00e9 au sein de l'organisation.<\/td><\/tr><tr><td><strong>Num\u00e9ro d'identit\u00e9<\/strong><\/td><td>Un identifiant unique pour la r\u00e9mun\u00e9ration ou l'administration.<\/td><\/tr><tr><td><strong>Profil de l'employ\u00e9<\/strong><\/td><td>D\u00e9finit le type d'acc\u00e8s de l'employ\u00e9 (par ex. Apprenant).<\/td><\/tr><tr><td><strong>Department<\/strong><\/td><td>Le d\u00e9partement auquel appartient l'employ\u00e9.<\/td><\/tr><tr><td><strong>ID OS de l'employ\u00e9<\/strong><\/td><td>Identifiant g\u00e9n\u00e9r\u00e9 par le syst\u00e8me ; non modifiable.<\/td><\/tr><tr><td><strong>ID externe<\/strong><\/td><td>Identifiant facultatif pour la liaison avec des syst\u00e8mes externes.<\/td><\/tr><tr><td><strong>Statut d'emploi<\/strong><\/td><td>Renseign\u00e9 automatiquement en fonction des dates de d\u00e9but\/fin : <em>Actuellement employ\u00e9, Non employ\u00e9, Pas encore commenc\u00e9.<\/em><\/td><\/tr><tr><td><strong>P\u00e9riode d'emploi<\/strong><\/td><td>D\u00e9finit les dates de d\u00e9but et de fin d'emploi.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n\n\n\n<p><strong>Remarques : <\/strong>Les modifications apport\u00e9es \u00e0 ces champs se synchroniseront automatiquement avec tous les autres produits Mapal OS, garantissant ainsi la coh\u00e9rence sur l'ensemble de la plateforme. La saisie pr\u00e9cise dans des champs tels que Site, Intitul\u00e9 de poste et Statut d'emploi est essentielle pour maintenir un fonctionnement et des rapports fluides dans l'\u00e9cosyst\u00e8me Mapal.<\/p>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Que se passe-t-il si je saisis une adresse e-mail en double ?<\/h2>\n\n\n\n\n\n\n<p>Si vous saisissez une adresse e-mail qui existe d\u00e9j\u00e0 dans le syst\u00e8me, Mapal OS reconna\u00eetra le doublon et le traitera automatiquement.<\/p>\n\n\n\n\n\n\n<ul class=\"wp-block-list\">\n\n<li>Les profils d'<strong>utilisateur existants ne seront pas \u00e9cras\u00e9s<\/strong>.<\/li>\n\n\n\n\n\n\n<li>Le syst\u00e8me garantit que chaque dossier d'employ\u00e9 reste li\u00e9 \u00e0 son profil d'utilisateur correct.<\/li>\n\n\n\n\n\n\n<li><strong>Statut de l'utilisateur<\/strong> (actif, inactif ou non d\u00e9marr\u00e9) est maintenu en fonction du <strong>statut d'emploi<\/strong> actuel de l'employ\u00e9.<\/li>\n<\/ul>\n\n\n\n\n\n\n<p>Cela emp\u00eache la r\u00e9attribution ou la fusion accidentelle de profils et garantit que l'acc\u00e8s bas\u00e9 sur l'e-mail reste coh\u00e9rent avec le statut actuel de chaque employ\u00e9 dans l'organisation.<\/p>\n\n\n\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n\n<p><strong>Remarque :<\/strong> V\u00e9rifiez toujours si une adresse e-mail est d\u00e9j\u00e0 associ\u00e9e \u00e0 un autre employ\u00e9 avant de la mettre \u00e0 jour. En cas de doute, contactez votre Customer Success Manager pour obtenir de l'aide.<\/p>\n<\/blockquote>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Supprimer un employ\u00e9<\/h2>\n\n\n\n\n\n\n<p>Bien qu'il soit possible de supprimer des employ\u00e9s de Mapal OS, nous vous recommandons vivement de <strong>d\u00e9sactiver les employ\u00e9s inactifs<\/strong> \u00e0 la place. Vous pouvez en savoir plus dans notre guide <a href=\"https:\/\/help.mapal-os.com\/fr\/uncategorised\/deactivate-an-employee-in-mapal-os-fr\/\">d\u00e9sactiver un employ\u00e9 dans Mapal OS<\/a>.<\/p>\n\n\n\n\n\n\n<p>Si vous \u00eates s\u00fbr que la suppression de l'employ\u00e9 est appropri\u00e9e, suivez ces \u00e9tapes :<\/p>\n\n\n\n\n\n\n<ul class=\"wp-block-list\">\n\n<li>Trouvez l'employ\u00e9. Vous pouvez utiliser le <strong>Filtre <\/strong>pour affiner votre recherche <strong>OU<\/strong> le bouton <strong>Rechercher<\/strong> pour trouver des noms sp\u00e9cifiques.<\/li>\n\n\n\n\n\n\n<li>Une fois que vous avez trouv\u00e9 l'employ\u00e9, s\u00e9lectionnez le bouton \u00e0 trois points \u00e0 l'extr\u00e9mit\u00e9 droite de la ligne et appuyez sur l'option <strong>Supprimer<\/strong>.<\/li>\n<\/ul>\n\n\n\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/migration\/KA-01975\/img1.jpg\" alt=\"A screenshot of a computer&lt;br&gt;&lt;br&gt;Description automatically generated\"><\/figure>\n\n\n\n\n\n\n<p><\/p>\n\n\n\n\n\n\n<ul class=\"wp-block-list\">\n\n<li>Une fen\u00eatre de confirmation s'affichera. S\u00e9lectionnez <strong>Supprimer<\/strong> pour terminer la suppression.<\/li>\n<\/ul>\n\n\n\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/migration\/KA-01975\/img2.jpg\" alt=\"A screenshot of a computer&lt;br&gt;&lt;br&gt;Description automatically generated\"><\/figure>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9sactiver des utilisateurs dans Mapal OS<\/h2>\n\n\n\n\n\n\n<p><strong data-end=\"3180\" data-start=\"3168\">Mapal OS<\/strong> fait la distinction entre les <strong data-end=\"3217\" data-start=\"3204\">Employ\u00e9s<\/strong> et les <strong data-end=\"3231\" data-start=\"3222\">Utilisateurs<\/strong>. Si vous marquez un <strong data-end=\"3260\" data-start=\"3248\">Employ\u00e9<\/strong> comme actif ou inactif, vous devez \u00e9galement mettre \u00e0 jour son statut d'<strong data-end=\"3319\" data-start=\"3311\">Utilisateur<\/strong> s\u00e9par\u00e9ment.<\/p>\n\n\n\n\n\n\n<p>Pour en savoir plus, consultez <strong data-end=\"3392\" data-start=\"3359\"><a href=\"https:\/\/help.mapal-os.com\/fr\/mapal-os-2\/gestion-des-utilisateurs\/utilisateurs-3\/garer-les-utilisateurs-sur-mapal-os\/\" rel=\"noopener\" data-end=\"3390\" data-start=\"3361\">G\u00e9rer les utilisateurs dans Mapal OS<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le module Configuration de Mapal OS permet aux gestionnaires de compte de g\u00e9rer les employ\u00e9s sur la plateforme afin de donner \u00e0 leur \u00e9quipe un acc\u00e8s appropri\u00e9 aux diff\u00e9rents produits de la famille Mapal.<\/p>\n","protected":false},"author":251210541,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[132422],"tags":[],"class_list":["post-12117","post","type-post","status-publish","format-standard","hentry","category-employes-1"],"acf":{"article_type":"default","post_id":"","post_url_text":"","post_url":"","info_box":{"title":"","info":""},"post_video":"","import_category":"","overview_item":null,"troubleshoot_case":null},"_links":{"self":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts\/12117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/users\/251210541"}],"replies":[{"embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/comments?post=12117"}],"version-history":[{"count":0,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/posts\/12117\/revisions"}],"wp:attachment":[{"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/media?parent=12117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/categories?post=12117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.mapal-os.com\/fr\/wp-json\/wp\/v2\/tags?post=12117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}